{"id":2314,"date":"2013-11-06T10:18:41","date_gmt":"2013-11-06T09:18:41","guid":{"rendered":"http:\/\/www.syntetyk.com\/Estudio\/?page_id=2314"},"modified":"2019-03-25T18:01:04","modified_gmt":"2019-03-25T17:01:04","slug":"politica-de-cookies","status":"publish","type":"page","link":"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/","title":{"rendered":"Pol\u00edtica de cookies"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Una&nbsp;<em>cookie<\/em>&nbsp;es un peque\u00f1o fichero de texto que se almacena en su navegador cuando visita casi cualquier p\u00e1gina web. Su utilidad es que la web sea capaz de recordar su visita cuando vuelva a navegar por esa p\u00e1gina. Las&nbsp;<em>cookies<\/em>&nbsp;suelen almacenar informaci\u00f3n de car\u00e1cter t\u00e9cnico, preferencias personales, personalizaci\u00f3n de contenidos, estad\u00edsticas de uso, enlaces a redes sociales, acceso a cuentas de usuario, etc. El objetivo de la&nbsp;<em>cookie<\/em>&nbsp;es adaptar el contenido de la web a su perfil y necesidades, sin&nbsp;<em>cookies<\/em>&nbsp;los servicios ofrecidos por cualquier p\u00e1gina se ver\u00edan mermados notablemente. Si desea consultar m\u00e1s informaci\u00f3n sobre qu\u00e9 son las&nbsp;<em>cookies<\/em>, qu\u00e9 almacenan, c\u00f3mo eliminarlas, desactivarlas, etc.,&nbsp;<a href=\"https:\/\/www.syntetyk.com\/Estudio\/mas-informacion-sobre-las-cookies\/\">le rogamos se dirija a este enlace.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cookies utilizadas en este sitio web<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Siguiendo las directrices de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos procedemos a detallar el uso de&nbsp;<em>cookies<\/em>&nbsp;que hace esta web con el fin de informarle con la m\u00e1xima exactitud posible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este sitio web utiliza las siguientes&nbsp;<strong>cookies propias<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Cookies de sesi\u00f3n, para garantizar que los usuarios que escriban comentarios en el blog sean humanos y no aplicaciones automatizadas. De esta forma se combate el&nbsp;<em>spam<\/em>.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Este sitio web utiliza las siguientes&nbsp;<strong>cookies de terceros<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Google Analytics: Almacena&nbsp;<em>cookies<\/em>&nbsp;para poder elaborar estad\u00edsticas sobre el tr\u00e1fico y volumen de visitas de esta web. Al utilizar este sitio web est\u00e1 consintiendo el tratamiento de informaci\u00f3n acerca de usted por Google. Por tanto, el ejercicio de cualquier derecho en este sentido deber\u00e1 hacerlo comunicando directamente con Google.<\/li><li>Redes sociales: Cada red social utiliza sus propias&nbsp;<em>cookies<\/em>&nbsp;para que usted pueda pinchar en botones del tipo&nbsp;<em>Me gusta<\/em>&nbsp;o&nbsp;<em>Compartir<\/em>.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Desactivaci\u00f3n o eliminaci\u00f3n de cookies<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En cualquier momento podr\u00e1 ejercer su derecho de desactivaci\u00f3n o eliminaci\u00f3n de cookies de este sitio web. Estas acciones se realizan de forma diferente en funci\u00f3n del navegador que est\u00e9 usando.&nbsp;<a href=\"https:\/\/www.syntetyk.com\/Estudio\/mas-informacion-sobre-las-cookies\/#navegadores\">Aqu\u00ed le dejamos una gu\u00eda r\u00e1pida para los navegadores m\u00e1s populares<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Notas adicionales<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Ni esta web ni sus representantes legales se hacen responsables ni del contenido ni de la veracidad de las pol\u00edticas de privacidad que puedan tener los terceros mencionados en esta pol\u00edtica de&nbsp;<em>cookies<\/em>.<\/li><li>Los navegadores web son las herramientas encargadas de almacenar las&nbsp;<em>cookies<\/em>&nbsp;y desde este lugar debe efectuar su derecho a eliminaci\u00f3n o desactivaci\u00f3n de las mismas. Ni esta web ni sus representantes legales pueden garantizar la correcta o incorrecta manipulaci\u00f3n de las&nbsp;<em>cookies<\/em>&nbsp;por parte de los mencionados navegadores.<\/li><li>En algunos casos es necesario instalar&nbsp;<em>cookies<\/em>&nbsp;para que el navegador no olvide su decisi\u00f3n de no aceptaci\u00f3n de las mismas.<\/li><li>En el caso de las&nbsp;<em>cookies<\/em>&nbsp;de Google Analytics, esta empresa almacena las&nbsp;<em>cookies<\/em>&nbsp;en servidores ubicados en Estados Unidos y se compromete a no compartirla con terceros, excepto en los casos en los que sea necesario para el funcionamiento del sistema o cuando la ley obligue a tal efecto. Seg\u00fan Google no guarda su direcci\u00f3n IP. Google Inc. es una compa\u00f1\u00eda adherida al Acuerdo de Puerto Seguro que garantiza que todos los datos transferidos ser\u00e1n tratados con un nivel de protecci\u00f3n acorde a la normativa europea. Puede consultar informaci\u00f3n detallada a este respecto&nbsp;<a href=\"http:\/\/safeharbor.export.gov\/companyinfo.aspx?id=16626\" target=\"_blank\" rel=\"noreferrer noopener\">en este enlace<\/a>. Si desea informaci\u00f3n sobre el uso que Google da a las cookies&nbsp;<a href=\"https:\/\/developers.google.com\/analytics\/devguides\/collection\/analyticsjs\/cookie-usage?hl=es&amp;csw=1\" target=\"_blank\" rel=\"noreferrer noopener\">le adjuntamos este otro enlace<\/a>.<\/li><li>Para cualquier duda o consulta acerca de esta pol\u00edtica de&nbsp;<em>cookies<\/em>&nbsp;no dude en comunicarse con nosotros a trav\u00e9s de la secci\u00f3n de contacto.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Una&nbsp;cookie&nbsp;es un peque\u00f1o fichero de texto que se almacena en su navegador cuando visita casi cualquier p\u00e1gina web. Su utilidad es que la web sea capaz de recordar su visita cuando vuelva a navegar por esa p\u00e1gina. Las&nbsp;cookies&nbsp;suelen almacenar informaci\u00f3n de car\u00e1cter t\u00e9cnico, preferencias personales, personalizaci\u00f3n de contenidos, estad\u00edsticas de uso, enlaces a redes sociales, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-2314","page","type-page","status-publish","hentry","wpbf-post"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Una cookie es un peque\u00f1o fichero de texto que se almacena en su navegador cuando visita casi cualquier p\u00e1gina web. Su utilidad es que la web sea capaz de recordar su visita cuando vuelva a navegar por esa p\u00e1gina. Las cookies suelen almacenar informaci\u00f3n de car\u00e1cter t\u00e9cnico, preferencias personales, personalizaci\u00f3n de contenidos, estad\u00edsticas de uso, enlaces a redes sociales,\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/politica-de-cookies\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/politica-de-cookies\\\/#listItem\",\"name\":\"Pol\\u00edtica de cookies\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/politica-de-cookies\\\/#listItem\",\"position\":2,\"name\":\"Pol\\u00edtica de cookies\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/#organization\",\"name\":\"Syntetyk\",\"description\":\"Estudio de dise\\u00f1o Syntetyk\",\"url\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/\",\"telephone\":\"+34963297751\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2019\\\/03\\\/Logo-Syntetyk@2x.png\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/politica-de-cookies\\\/#organizationLogo\",\"width\":372,\"height\":86},\"image\":{\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/politica-de-cookies\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/Syntetyk\",\"https:\\\/\\\/www.instagram.com\\\/syntetyk\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkkJS9bqCYcC0OiT8woTLpQ\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/politica-de-cookies\\\/#webpage\",\"url\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/politica-de-cookies\\\/\",\"name\":\"Pol\\u00edtica de cookies | Syntetyk Estudio\",\"description\":\"Una cookie es un peque\\u00f1o fichero de texto que se almacena en su navegador cuando visita casi cualquier p\\u00e1gina web. Su utilidad es que la web sea capaz de recordar su visita cuando vuelva a navegar por esa p\\u00e1gina. Las cookies suelen almacenar informaci\\u00f3n de car\\u00e1cter t\\u00e9cnico, preferencias personales, personalizaci\\u00f3n de contenidos, estad\\u00edsticas de uso, enlaces a redes sociales,\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/politica-de-cookies\\\/#breadcrumblist\"},\"datePublished\":\"2013-11-06T10:18:41+01:00\",\"dateModified\":\"2019-03-25T18:01:04+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/#website\",\"url\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/\",\"name\":\"Syntetyk Estudio\",\"description\":\"Estudio de dise\\u00f1o Syntetyk\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/syntetyk.com\\\/Estudio\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Pol\u00edtica de cookies | Syntetyk Estudio","description":"Una cookie es un peque\u00f1o fichero de texto que se almacena en su navegador cuando visita casi cualquier p\u00e1gina web. Su utilidad es que la web sea capaz de recordar su visita cuando vuelva a navegar por esa p\u00e1gina. Las cookies suelen almacenar informaci\u00f3n de car\u00e1cter t\u00e9cnico, preferencias personales, personalizaci\u00f3n de contenidos, estad\u00edsticas de uso, enlaces a redes sociales,","canonical_url":"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/syntetyk.com\/Estudio#listItem","position":1,"name":"Home","item":"https:\/\/syntetyk.com\/Estudio","nextItem":{"@type":"ListItem","@id":"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/#listItem","name":"Pol\u00edtica de cookies"}},{"@type":"ListItem","@id":"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/#listItem","position":2,"name":"Pol\u00edtica de cookies","previousItem":{"@type":"ListItem","@id":"https:\/\/syntetyk.com\/Estudio#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/syntetyk.com\/Estudio\/#organization","name":"Syntetyk","description":"Estudio de dise\u00f1o Syntetyk","url":"https:\/\/syntetyk.com\/Estudio\/","telephone":"+34963297751","logo":{"@type":"ImageObject","url":"https:\/\/syntetyk.com\/Estudio\/wp-content\/uploads\/sites\/4\/2019\/03\/Logo-Syntetyk@2x.png","@id":"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/#organizationLogo","width":372,"height":86},"image":{"@id":"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/Syntetyk","https:\/\/www.instagram.com\/syntetyk\/","https:\/\/www.youtube.com\/channel\/UCkkJS9bqCYcC0OiT8woTLpQ"]},{"@type":"WebPage","@id":"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/#webpage","url":"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/","name":"Pol\u00edtica de cookies | Syntetyk Estudio","description":"Una cookie es un peque\u00f1o fichero de texto que se almacena en su navegador cuando visita casi cualquier p\u00e1gina web. Su utilidad es que la web sea capaz de recordar su visita cuando vuelva a navegar por esa p\u00e1gina. Las cookies suelen almacenar informaci\u00f3n de car\u00e1cter t\u00e9cnico, preferencias personales, personalizaci\u00f3n de contenidos, estad\u00edsticas de uso, enlaces a redes sociales,","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/syntetyk.com\/Estudio\/#website"},"breadcrumb":{"@id":"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/#breadcrumblist"},"datePublished":"2013-11-06T10:18:41+01:00","dateModified":"2019-03-25T18:01:04+01:00"},{"@type":"WebSite","@id":"https:\/\/syntetyk.com\/Estudio\/#website","url":"https:\/\/syntetyk.com\/Estudio\/","name":"Syntetyk Estudio","description":"Estudio de dise\u00f1o Syntetyk","inLanguage":"es-ES","publisher":{"@id":"https:\/\/syntetyk.com\/Estudio\/#organization"}}]}},"aioseo_meta_data":{"post_id":"2314","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 21:54:05","updated":"2025-06-04 00:46:10","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/syntetyk.com\/Estudio\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPol\u00edtica de cookies\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/syntetyk.com\/Estudio"},{"label":"Pol\u00edtica de cookies","link":"https:\/\/syntetyk.com\/Estudio\/politica-de-cookies\/"}],"jetpack_shortlink":"https:\/\/wp.me\/P39d40-Bk","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/syntetyk.com\/Estudio\/wp-json\/wp\/v2\/pages\/2314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syntetyk.com\/Estudio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/syntetyk.com\/Estudio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/syntetyk.com\/Estudio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/syntetyk.com\/Estudio\/wp-json\/wp\/v2\/comments?post=2314"}],"version-history":[{"count":2,"href":"https:\/\/syntetyk.com\/Estudio\/wp-json\/wp\/v2\/pages\/2314\/revisions"}],"predecessor-version":[{"id":2566,"href":"https:\/\/syntetyk.com\/Estudio\/wp-json\/wp\/v2\/pages\/2314\/revisions\/2566"}],"wp:attachment":[{"href":"https:\/\/syntetyk.com\/Estudio\/wp-json\/wp\/v2\/media?parent=2314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}