{"id":75,"date":"2019-04-12T11:37:54","date_gmt":"2019-04-12T09:37:54","guid":{"rendered":"https:\/\/www.syntetyk.com\/store\/?post_type=product&#038;p=75"},"modified":"2019-05-22T09:37:48","modified_gmt":"2019-05-22T07:37:48","slug":"catalogo-brew-toys","status":"publish","type":"product","link":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/","title":{"rendered":"Cat\u00e1logo exposici\u00f3n Brew Toys (pdf)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<div class=\"biografia\">\n<div title=\"Page 5\">\n<div>\n<div>\n<p>Brew Toys es una exposici\u00f3n que naci\u00f3 durante el Pecha Kucha Night Valencia Vol. 17. Cuando Syntetyk y Zeta Beer nos retamos mutuamente a trav\u00e9s de Twitter, sin conocernos de nada.<\/p>\n<p>A partir de ese momento empez\u00f3 a tomar cuerpo, gracias a Vinyl Escape, y al nexo que nos une a los tres pilares: Valencia. Esta muestra es una exposici\u00f3n con una fuerte carga valenciana que se completa con representaci\u00f3n nacional por cuenta de Wip Toys.<\/p>\n<\/div>\n<div>\n<p>Brew Toys es un ejercicio de diversi\u00f3n en el que juntamos Art Toys y cerveza fresca. Dos sujetos interesantes por separado y apasionantes juntos.<\/p>\n<p>Participamos en esta exposici\u00f3n:<br \/>\nHx Studio, Flukegraf, Godhay, The Criaturas, Jalos, Que Maten Al Dise\u00f1ador, CranioDSGN, Cot\u00e9 Escriv\u00e1 Discoh, Estudi Cercle, Jorge Lawerta, Jos\u00e9 Rico y Mar\u00eda Rico, Nuria Balaguer, Sara Sanz, Twee Muizen, Joan Quir\u00f3s, Kike Correcher y Syntetyk.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"clear\"><\/div>\n","protected":false},"featured_media":76,"template":"","meta":{"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[19],"product_tag":[],"class_list":["post-75","product","type-product","status-publish","has-post-thumbnail","product_cat-libros","wpbf-post","instock","sold-individually","product-type-external"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\n\t\t<!-- Global site tag (gtag.js) - Google Analytics -->\n<script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=UA-20546435-29\"><\/script>\n<script>\n window.dataLayer = window.dataLayer || [];\n function gtag(){dataLayer.push(arguments);}\n gtag('js', new Date());\n\n gtag('config', 'UA-20546435-29');\n<\/script>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/producto\\\/catalogo-brew-toys\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/syntetyk.com\\\/store\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/categoria-producto\\\/libros\\\/#listItem\",\"name\":\"Libros\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/categoria-producto\\\/libros\\\/#listItem\",\"position\":2,\"name\":\"Libros\",\"item\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/categoria-producto\\\/libros\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/producto\\\/catalogo-brew-toys\\\/#listItem\",\"name\":\"Cat\\u00e1logo exposici\\u00f3n Brew Toys (pdf)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/producto\\\/catalogo-brew-toys\\\/#listItem\",\"position\":3,\"name\":\"Cat\\u00e1logo exposici\\u00f3n Brew Toys (pdf)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/categoria-producto\\\/libros\\\/#listItem\",\"name\":\"Libros\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/producto\\\/catalogo-brew-toys\\\/#itempage\",\"url\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/producto\\\/catalogo-brew-toys\\\/\",\"name\":\"Cat\\u00e1logo exposici\\u00f3n Brew Toys (pdf) | Syntetyk Store\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/producto\\\/catalogo-brew-toys\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/04\\\/PrevioPortada.jpg\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/producto\\\/catalogo-brew-toys\\\/#mainImage\",\"width\":512,\"height\":512},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/producto\\\/catalogo-brew-toys\\\/#mainImage\"},\"datePublished\":\"2019-04-12T11:37:54+02:00\",\"dateModified\":\"2019-05-22T09:37:48+02:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/#organization\",\"name\":\"Syntetyk\",\"description\":\"Tienda del estudio de dise\\u00f1o Syntetyk\",\"url\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2019\\\/04\\\/Logo-SyntetykStore@2x.png\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/producto\\\/catalogo-brew-toys\\\/#organizationLogo\",\"width\":373,\"height\":120},\"image\":{\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/producto\\\/catalogo-brew-toys\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/twitter.com\\\/Syntetyk\",\"https:\\\/\\\/www.instagram.com\\\/syntetyk\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCkkJS9bqCYcC0OiT8woTLpQ\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/#website\",\"url\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/\",\"name\":\"Syntetyk Store\",\"description\":\"Tienda del estudio de dise\\u00f1o Syntetyk\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/syntetyk.com\\\/store\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Cat\u00e1logo exposici\u00f3n Brew Toys (pdf) | Syntetyk Store","description":"","canonical_url":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":"&lt;!-- Global site tag (gtag.js) - Google Analytics --&gt;\n&lt;script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=UA-20546435-29\"&gt;&lt;\/script&gt;\n&lt;script&gt;\n&nbsp;window.dataLayer = window.dataLayer || [];\n&nbsp;function gtag(){dataLayer.push(arguments);}\n&nbsp;gtag('js', new Date());\n\n&nbsp;gtag('config', 'UA-20546435-29');\n&lt;\/script&gt;"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/syntetyk.com\/store#listItem","position":1,"name":"Home","item":"https:\/\/syntetyk.com\/store","nextItem":{"@type":"ListItem","@id":"https:\/\/syntetyk.com\/store\/categoria-producto\/libros\/#listItem","name":"Libros"}},{"@type":"ListItem","@id":"https:\/\/syntetyk.com\/store\/categoria-producto\/libros\/#listItem","position":2,"name":"Libros","item":"https:\/\/syntetyk.com\/store\/categoria-producto\/libros\/","nextItem":{"@type":"ListItem","@id":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/#listItem","name":"Cat\u00e1logo exposici\u00f3n Brew Toys (pdf)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/syntetyk.com\/store#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/#listItem","position":3,"name":"Cat\u00e1logo exposici\u00f3n Brew Toys (pdf)","previousItem":{"@type":"ListItem","@id":"https:\/\/syntetyk.com\/store\/categoria-producto\/libros\/#listItem","name":"Libros"}}]},{"@type":"ItemPage","@id":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/#itempage","url":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/","name":"Cat\u00e1logo exposici\u00f3n Brew Toys (pdf) | Syntetyk Store","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/syntetyk.com\/store\/#website"},"breadcrumb":{"@id":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/syntetyk.com\/store\/wp-content\/uploads\/sites\/7\/2019\/04\/PrevioPortada.jpg","@id":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/#mainImage","width":512,"height":512},"primaryImageOfPage":{"@id":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/#mainImage"},"datePublished":"2019-04-12T11:37:54+02:00","dateModified":"2019-05-22T09:37:48+02:00"},{"@type":"Organization","@id":"https:\/\/syntetyk.com\/store\/#organization","name":"Syntetyk","description":"Tienda del estudio de dise\u00f1o Syntetyk","url":"https:\/\/syntetyk.com\/store\/","logo":{"@type":"ImageObject","url":"https:\/\/syntetyk.com\/store\/wp-content\/uploads\/sites\/7\/2019\/04\/Logo-SyntetykStore@2x.png","@id":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/#organizationLogo","width":373,"height":120},"image":{"@id":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/#organizationLogo"},"sameAs":["https:\/\/twitter.com\/Syntetyk","https:\/\/www.instagram.com\/syntetyk\/","https:\/\/www.youtube.com\/channel\/UCkkJS9bqCYcC0OiT8woTLpQ"]},{"@type":"WebSite","@id":"https:\/\/syntetyk.com\/store\/#website","url":"https:\/\/syntetyk.com\/store\/","name":"Syntetyk Store","description":"Tienda del estudio de dise\u00f1o Syntetyk","inLanguage":"es-ES","publisher":{"@id":"https:\/\/syntetyk.com\/store\/#organization"}}]}},"aioseo_meta_data":{"post_id":"75","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-20 21:26:39","updated":"2025-06-03 21:56:30","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/syntetyk.com\/store\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/syntetyk.com\/store\/categoria-producto\/libros\/\" title=\"Libros\">Libros<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCat\u00e1logo exposici\u00f3n Brew Toys (pdf)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/syntetyk.com\/store"},{"label":"Libros","link":"https:\/\/syntetyk.com\/store\/categoria-producto\/libros\/"},{"label":"Cat\u00e1logo exposici\u00f3n Brew Toys (pdf)","link":"https:\/\/syntetyk.com\/store\/producto\/catalogo-brew-toys\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/syntetyk.com\/store\/wp-json\/wp\/v2\/product\/75","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syntetyk.com\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/syntetyk.com\/store\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/syntetyk.com\/store\/wp-json\/wp\/v2\/media\/76"}],"wp:attachment":[{"href":"https:\/\/syntetyk.com\/store\/wp-json\/wp\/v2\/media?parent=75"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/syntetyk.com\/store\/wp-json\/wp\/v2\/product_brand?post=75"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/syntetyk.com\/store\/wp-json\/wp\/v2\/product_cat?post=75"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/syntetyk.com\/store\/wp-json\/wp\/v2\/product_tag?post=75"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}